{"id":42705,"date":"2023-05-29T13:02:54","date_gmt":"2023-05-29T11:02:54","guid":{"rendered":"https:\/\/triptherapie.nl\/?page_id=42705"},"modified":"2026-01-16T16:29:00","modified_gmt":"2026-01-16T15:29:00","slug":"lsd-sitzung","status":"publish","type":"page","link":"https:\/\/triptherapie.nl\/de\/lsd-sessie\/","title":{"rendered":"LSD-Sitzung"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"42705\" class=\"elementor elementor-42705\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8ef24 e-flex e-con-boxed e-con e-parent\" data-id=\"7b8ef24\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd0b268 elementor-widget elementor-widget-heading\" data-id=\"cd0b268\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"legale-lsd-sessie-in-nederland\">Legale LSD-Session in den Niederlanden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfb7fe7 e-flex e-con-boxed e-con e-parent\" data-id=\"cfb7fe7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-da6e48d e-con-full e-flex e-con e-child\" data-id=\"da6e48d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53587c0 elementor-widget elementor-widget-text-editor\" data-id=\"53587c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>In den Niederlanden ist LSD illegal, da es auf der Opiumliste als harte Droge mit hohem Gefahren- und Suchtpotenzial gef\u00fchrt wird. LSD ist als Droge der Liste I eingestuft, was bedeutet, dass es als Substanz ohne medizinischen Nutzen und mit hohem Missbrauchs- und Suchtrisiko gilt. Besitz, Herstellung und Verkauf von LSD (und anderen harten Drogen wie Kokain und Heroin) sind daher nach dem niederl\u00e4ndischen Opiumgesetz strafbar. Das Gesetz dient dem Schutz der \u00f6ffentlichen Gesundheit und der Bek\u00e4mpfung der Drogenkriminalit\u00e4t. Verschiedenen Studien zufolge k\u00f6nnte LSD jedoch durchaus einen medizinischen Nutzen haben, weshalb seine Aufnahme in Liste I des Opiumgesetzes als ungerechtfertigt gilt.<\/p><p>In den Niederlanden k\u00f6nnen wir legal LSD-Sitzungen anbieten, indem wir ein legales Analogon anstelle von illegalem LSD verwenden. Dieses legale LSD-Analogon hat nach Einnahme und Verstoffwechselung im sauren Milieu des K\u00f6rpers exakt dieselbe Wirkung wie LSD. Daher werden Sitzungen mit diesem legalen Analogon ebenfalls als LSD-Sitzungen bezeichnet, obwohl sie gesetzeskonform sind. Laut geltender Gesetzgebung ist eine LSD-Sitzung keine offizielle Behandlung und ersetzt keine regul\u00e4re Psychotherapie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a28eaf e-flex e-con-boxed e-con e-parent\" data-id=\"7a28eaf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd6631 elementor-widget elementor-widget-heading\" data-id=\"2cd6631\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"wetenschappelijke-bevindingen\">Wissenschaftliche Erkenntnisse<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a7876 elementor-widget elementor-widget-text-editor\" data-id=\"a7a7876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>In den letzten f\u00fcnf Jahren ist das Interesse an der Erforschung von LSD (Lysergs\u00e4urediethylamid) und seinem Potenzial zur Behandlung verschiedener psychischer Erkrankungen wieder gestiegen. Fr\u00fchere Studien aus den 1950er- und 1960er-Jahren, die das therapeutische Potenzial von LSD aufgezeigt hatten, wurden w\u00e4hrend des US-amerikanischen Drogenkriegs abgebrochen.<br \/><br \/>J\u00fcngste Studien haben gezeigt, dass LSD zur Linderung von Symptomen von Depressionen, Angstzust\u00e4nden und Suchterkrankungen eingesetzt werden kann. Derzeit wird erforscht, inwieweit LSD das Ego reduzieren kann, was zu einem st\u00e4rkeren Gef\u00fchl der Verbundenheit mit anderen und der Welt um uns herum f\u00fchren kann.<br \/><br \/>Die Universit\u00e4t Basel hat k\u00fcrzlich eine neue Studie gestartet, in der LSD mit Virtual-Reality-Therapie kombiniert wird, um zu untersuchen, ob dies die Wirksamkeit der Behandlung steigert. \u00dcber das therapeutische Potenzial von LSD wird noch viel entdeckt, und in den kommenden Jahren werden zweifellos weitere interessante Ergebnisse ver\u00f6ffentlicht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b5a496 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9b5a496\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?term=Lysergic\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00dcberblick \u00fcber wissenschaftliche Studien<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5edc82b e-flex e-con-boxed e-con e-parent\" data-id=\"5edc82b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de4d40a elementor-widget elementor-widget-heading\" data-id=\"de4d40a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"de-werking-van-lsd\">Die Auswirkungen von LSD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9cea498 e-flex e-con-boxed e-con e-parent\" data-id=\"9cea498\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e3d4c45 e-con-full e-flex e-con e-child\" data-id=\"e3d4c45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68b7d92 elementor-widget elementor-widget-text-editor\" data-id=\"68b7d92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>W\u00e4hrend einer LSD-Session treten die ersten sp\u00fcrbaren Effekte etwa eine halbe Stunde nach der Einnahme ein. Der H\u00f6hepunkt der Wirkung wird im Durchschnitt nach einer Stunde und f\u00fcnfzehn Minuten erreicht. Die Wirkung von LSD l\u00e4sst sich in subjektive Erfahrungen und messbare Ver\u00e4nderungen im Gehirn unterteilen. Lesen Sie auf den folgenden Seiten mehr \u00fcber die Ver\u00e4nderungen der Gehirnfunktionen und die ver\u00e4nderte Wahrnehmung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfe06a1 e-flex e-con-boxed e-con e-child\" data-id=\"cfe06a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d46ac5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8d46ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/triptherapie.nl\/de\/die-auswirkungen-von-lsd\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Wie LSD wirkt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07f7e77 e-con-full e-flex e-con e-child\" data-id=\"07f7e77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b7e1cf elementor-widget elementor-widget-image\" data-id=\"4b7e1cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"736\" height=\"320\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2023\/05\/LSD-sessie-tijd.webp?wsr\" class=\"attachment-large size-large wp-image-42718\" alt=\"Dauer der LSD-Therapie\" srcset=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2023\/05\/LSD-sessie-tijd.webp 736w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2023\/05\/LSD-sessie-tijd-300x130.webp 300w\" sizes=\"(max-width: 736px) 100vw, 736px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14b8c45 e-flex e-con-boxed e-con e-parent\" data-id=\"14b8c45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5064315 elementor-widget elementor-widget-heading\" data-id=\"5064315\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"de-contra-indicaties\">Die Kontraindikationen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18ae1a4 e-flex e-con-boxed e-con e-parent\" data-id=\"18ae1a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65b4046 e-con-full e-flex e-con e-child\" data-id=\"65b4046\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22ed45b elementor-widget elementor-widget-text-editor\" data-id=\"22ed45b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Laut verschiedenen Studien ist LSD, \u00e4hnlich wie Psilocybin, ein sehr sicheres Psychedelikum. Die Kombination mit bestimmten Medikamenten oder Erkrankungen kann jedoch gef\u00e4hrlich sein. Daher ist ein Vorgespr\u00e4ch vor der Einnahme von LSD unerl\u00e4sslich. Dieses Vorgespr\u00e4ch dient der Abkl\u00e4rung und hilft festzustellen, ob ein erh\u00f6htes Risiko f\u00fcr Nebenwirkungen wie Panikattacken, Paranoia, Halluzinationen und andere psychische Probleme besteht. Dar\u00fcber hinaus bildet es die Grundlage f\u00fcr eine individuelle Beratung zur Vorbereitung auf die LSD-Einnahme.<br \/><br \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6486354 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6486354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/triptherapie.nl\/de\/aufnahmetherapie\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Starten Sie die Ansaugung.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-216f18c e-con-full e-flex e-con e-child\" data-id=\"216f18c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59e9805 elementor-widget elementor-widget-text-editor\" data-id=\"59e9805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><\/p><ul class=\"wp-block-list\"><li>Lithium-Medikament<\/li> <li>Tramadol-Medikament<\/li> <li>MAO-Hemmer, SSRIs, Antidepressiva oder Antipsychotika<\/li> <li>Ein erh\u00f6htes Psychoserisiko<\/li> <li>Empfindlichkeit gegen\u00fcber Paranoia<\/li> <li>Sensibilit\u00e4t gegen\u00fcber Verdachtsmomenten<\/li> <li>Bluthochdruck oder Herzprobleme<\/li> <li>J\u00fcngere als 23 Jahre<\/li> <li>Schwangerschaft und\/oder Stillen<\/li> <li>Posttraumatische Belastungsst\u00f6rung und schweres Trauma<\/li><\/ul><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce63021 e-flex e-con-boxed e-con e-parent\" data-id=\"ce63021\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a003dd5 elementor-widget elementor-widget-heading\" data-id=\"a003dd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"een-lsd-sessie-boeken\">Buche eine LSD-Session<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f110876 e-flex e-con-boxed e-con e-parent\" data-id=\"f110876\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7a08b0d e-con-full e-flex e-con e-child\" data-id=\"7a08b0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-babfff9 elementor-widget elementor-widget-text-editor\" data-id=\"babfff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9d8511 elementor-widget elementor-widget-text-editor\" data-id=\"e9d8511\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>W\u00e4hlen Sie den Ort f\u00fcr Ihre LSD-Sitzung selbst. Je nach Wunsch besuchen wir Sie gerne zu Hause, im Hotel, in einer Ferienwohnung oder in einer Airbnb-Unterkunft. Alternativ bieten wir diese Sitzungen auch in unseren R\u00e4umlichkeiten in Schiedam an. Wir k\u00f6nnen Einzelsitzungen sowie Gruppensitzungen mit bis zu acht Personen durchf\u00fchren. Wenn eine LSD-Sitzung zur therapeutischen Wirkung gebucht wird, empfehlen wir eine kleine Gruppengr\u00f6\u00dfe.<\/p>\n<p>Die Therapeuten, die LSD-Sitzungen anbieten, sind Marcel, Sascha, Ronald, Gijs, Reineke und Janneke. Sie k\u00f6nnen \u00fcber die untenstehende \u00dcbersicht auf die Profilseiten dieser Therapeuten zugreifen oder die Kosten einer LSD-Sitzung an Ihrem Standort mit dem Kostenrechner ermitteln.<\/p>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9c0b71 e-con-full e-flex e-con e-child\" data-id=\"e9c0b71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd446d3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"dd446d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/triptherapie.nl\/de\/psychedelisches-loft-schiedam\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Psychedelic Loft Schiedam<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fb628f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6fb628f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/triptherapie.nl\/de\/kontakt\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktieren Sie uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f659d9b e-con-full e-flex e-con e-child\" data-id=\"f659d9b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f96c498 elementor-widget elementor-widget-heading\" data-id=\"f96c498\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00dcbungseinheit zum Berechnungsmodul zu Hause<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c928dd elementor-widget elementor-widget-text-editor\" data-id=\"2c928dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Adresse oder Ortsnamen eingeben:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eff63ad elementor-widget elementor-widget-html\" data-id=\"eff63ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div class=\"tt-bereken-widget\" role=\"search\" aria-label=\"Preis vor Ort berechnen\">\n  <label for=\"tt-adres\" class=\"tt-label\"><\/label>\n  <input id=\"tt-adres\" type=\"text\" placeholder=\"Zum Beispiel Amsterdam oder vollst\u00e4ndige Adresse\"\n         autocomplete=\"street-address\" \/>\n  <a id=\"tt-bereken\" class=\"elementor-button elementor-size-md\" role=\"button\">\n    <span class=\"elementor-button-content-wrapper\">\n      <span class=\"elementor-button-text\">Berechnen<\/span>\n    <\/span>\n  <\/a>\n  <p class=\"tt-help\"><\/p>\n<\/div>\n\n<script>\n(function(){\n  const input   = document.getElementById('tt-adres');\n  const button  = document.getElementById('tt-bereken');\n\n  function go(){\n    const val = (input.value || '').trim();\n    if(!val){\n      input.focus();\n      return;\n    }\n    const base = 'https:\/\/triptherapie.nl\/reserveringen\/werkgebied\/';\n    const params = new URLSearchParams({\n      guide: 'Marcel,Janneke,Gijs,Sascha,Ronald,Reineke',\n      zoek: val\n    });\n    const url = base + '?' + params.toString() + '#prijsberekening-sessie-op-locatie';\n    window.open(url, '_blank', 'noopener');\n  }\n\n  button.addEventListener('click', go);\n  input.addEventListener('keydown', function(e){\n    if(e.key === 'Enter'){ e.preventDefault(); go(); }\n  });\n})();\n<\/script>\n\n<style>\n.tt-bereken-widget{\n  display:grid;\n  gap:10px;\n  max-width:500px;\n  margin:0 auto;\n  text-align:center;\n}\n.tt-bereken-widget .tt-label{\n  font-size:.95rem;\n}\n.tt-bereken-widget input{\n  padding:.75rem 1rem;\n  border:1px solid #ddd;\n  border-radius:6px;\n  width:100%;\n  font-size:1rem;\n}\n.tt-bereken-widget .elementor-button{\n  display:inline-block;\n  text-decoration:none;\n  cursor:pointer;\n  width:auto;\n  margin:0 auto;\n}\n.tt-bereken-widget .tt-help{\n  margin:0;\n  font-size:.9rem;\n  opacity:.8;\n}\n<\/style>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82185a8 e-flex e-con-boxed e-con e-parent\" data-id=\"82185a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-723b8c3 elementor-widget elementor-widget-heading\" data-id=\"723b8c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"over-de-lsd-begeleiders\">\u00dcber die LSD-Berater<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc72641 elementor-widget elementor-widget-text-editor\" data-id=\"cc72641\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie mehr \u00fcber Therapeuten und Tripsitter erfahren m\u00f6chten, die mit LSD und seinen Analoga arbeiten, k\u00f6nnen Sie sich unten mit ihnen vertraut machen, ihre LinkedIn-Profile besuchen, ihre Verf\u00fcgbarkeit \u00fcber die Kalenderoption pr\u00fcfen oder die Bewertungen anderer Klienten \u00fcber den jeweiligen Therapeuten lesen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3f4e71 e-flex e-con-boxed e-con e-parent\" data-id=\"d3f4e71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e21f7b elementor-widget elementor-widget-template\" data-id=\"1e21f7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"47556\" class=\"elementor elementor-47556\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90971c9 e-grid e-con-boxed e-con e-child\" data-id=\"90971c9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6a760020 e-flex e-con-boxed e-con e-child\" data-id=\"6a760020\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f22ed51 elementor-widget elementor-widget-image\" data-id=\"f22ed51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/triptherapie.nl\/de\/personal\/marcel\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Marcel-van-der-Putten-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-56126\" alt=\"Marcel van der Putten Portrait\" srcset=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Marcel-van-der-Putten-150x150.png 150w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Marcel-van-der-Putten-300x300.png 300w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Marcel-van-der-Putten-12x12.png 12w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Marcel-van-der-Putten.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d631683 e-flex e-con-boxed e-con e-child\" data-id=\"3d631683\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12f6afb3 elementor-widget elementor-widget-heading\" data-id=\"12f6afb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"marcel-van-der-putten\"><a href=\"https:\/\/triptherapie.nl\/de\/personal\/marcel\/\">Marcel van der Putten<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74164c1 elementor-widget elementor-widget-heading\" data-id=\"74164c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Gr\u00fcnder von Triptherapie &amp; Psychedelischer F\u00fchrer<\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47d72bec e-flex e-con-boxed e-con e-child\" data-id=\"47d72bec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80db0bd elementor-widget elementor-widget-heading\" data-id=\"80db0bd\" data-element_type=\"widget\" data-e-type=\"widget\" aria-label=\"Sprachtherapeut\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> \ud83c\uddf3\ud83c\uddf1 \ud83c\uddec\ud83c\udde7 <\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ecde87e e-con-full e-flex e-con e-child\" data-id=\"ecde87e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4907a9 elementor-invisible elementor-widget elementor-widget-global elementor-global-46886 elementor-widget-counter\" data-id=\"c4907a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" aria-live=\"polite\" aria-label=\"Anzahl der gef\u00fchrten psychedelischen Sitzungen\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Sitzungen<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"2459\" data-from-value=\"2439\">2439<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20884dde elementor-widget elementor-widget-text-editor\" data-id=\"20884dde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Mit einem Hintergrund in Chemie, einer Leidenschaft f\u00fcr Philosophie sowie umfassenden Kenntnissen in den Bereichen Psychologie und Gesundheit verfolgt er einen ganzheitlichen Ansatz. Marcel ist hauptberuflich als Trip-Begleiter t\u00e4tig. Mit mehr als 2.450 begleiteten Sitzungen verf\u00fcgt Marcel \u00fcber die meiste Erfahrung in unserem Team.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3089a18b e-flex e-con-boxed e-con e-child\" data-id=\"3089a18b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-357f50e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"357f50e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a3a6f78 e-flex e-con-boxed e-con e-child\" data-id=\"a3a6f78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18217c40 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"18217c40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/in\/marcel-van-der-putten-2096aa195\/\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\"LinkedIn Marcel\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4601b66e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4601b66e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/triptherapie.nl\/de\/reservierungen\/marcels-agenda\/\" target=\"_blank\" aria-label=\"Verf\u00fcgbarkeit Marcel\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dad6325 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1dad6325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/trip-forum.nl\/recensie-truffel-therapie-marcel\/\" target=\"_blank\" aria-label=\"Rezensionen Marcel\" rel=\"noopener\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-thumbs-up\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M466.27 286.69C475.04 271.84 480 256 480 236.85c0-44.015-37.218-85.58-85.82-85.58H357.7c4.92-12.81 8.85-28.13 8.85-46.54C366.55 31.936 328.86 0 271.28 0c-61.607 0-58.093 94.933-71.76 108.6-22.747 22.747-49.615 66.447-68.76 83.4H32c-17.673 0-32 14.327-32 32v240c0 17.673 14.327 32 32 32h64c14.893 0 27.408-10.174 30.978-23.95 44.509 1.001 75.06 39.94 177.802 39.94 7.22 0 15.22.01 22.22.01 77.117 0 111.986-39.423 112.94-95.33 13.319-18.425 20.299-43.122 17.34-66.99 9.854-18.452 13.664-40.343 8.99-62.99zm-61.75 53.83c12.56 21.13 1.26 49.41-13.94 57.57 7.7 48.78-17.608 65.9-53.12 65.9h-37.82c-71.639 0-118.029-37.82-171.64-37.82V240h10.92c28.36 0 67.98-70.89 94.54-97.46 28.36-28.36 18.91-75.63 37.82-94.54 47.27 0 47.27 32.98 47.27 56.73 0 39.17-28.36 56.72-28.36 94.54h103.99c21.11 0 37.73 18.91 37.82 37.82.09 18.9-12.82 37.81-22.27 37.81 13.489 14.555 16.371 45.236-5.21 65.62zM88 432c0 13.255-10.745 24-24 24s-24-10.745-24-24 10.745-24 24-24 24 10.745 24 24z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-525ee36b e-flex e-con-boxed e-con e-child\" data-id=\"525ee36b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-147d62ce elementor-widget elementor-widget-image\" data-id=\"147d62ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/triptherapie.nl\/de\/personal\/ronald\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2023\/04\/Ronald-no-bg-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-41482\" alt=\"Ronald Hochstenbach, psychosozialer Therapeut und psychedelischer Therapeut mit AGB-Code\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1af9000f e-flex e-con-boxed e-con e-child\" data-id=\"1af9000f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-182e3ac8 elementor-widget elementor-widget-heading\" data-id=\"182e3ac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"ronald-hochstenbach\"><a href=\"https:\/\/triptherapie.nl\/de\/personal\/ronald\/\">Ronald Hochstenbach<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64a78d16 elementor-widget elementor-widget-heading\" data-id=\"64a78d16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Psychosozialer Therapeut<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-932d271 elementor-widget elementor-widget-heading\" data-id=\"932d271\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/rbcz.nu\/therapeut\/hochstenbach\/#:~:text=AGB%20code%3A%2090%2F115669\" target=\"_blank\" rel=\"nofollow noopener\">RBCZ-Registrierung mit AGB-Code 90115669<\/a><\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dacb1c3 e-flex e-con-boxed e-con e-child\" data-id=\"4dacb1c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4bcc6f elementor-widget elementor-widget-heading\" data-id=\"2d4bcc6f\" data-element_type=\"widget\" data-e-type=\"widget\" aria-label=\"Sprachtherapeut\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> \ud83c\uddf3\ud83c\uddf1 \ud83c\uddec\ud83c\udde7 \ud83c\udde9\ud83c\uddea<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc97160 e-con-full e-flex e-con e-child\" data-id=\"fc97160\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-996eca7 elementor-invisible elementor-widget elementor-widget-global elementor-global-46893 elementor-widget-counter\" data-id=\"996eca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" aria-live=\"polite\" aria-label=\"Anzahl der gef\u00fchrten psychedelischen Sitzungen\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Sitzungen<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1500\" data-to-value=\"387\" data-from-value=\"384\">384<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd4dc37 elementor-widget elementor-widget-text-editor\" data-id=\"fd4dc37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ronald ist psychosoziale Therapeutin und hat folgende Ausbildungen absolviert: Jungianische philosophische Therapie, Psychodrama-Therapie, Master Voice Dialogue, Transformationspsychologie, Internal Family System (IFS), Achtsamkeits- und Mitgef\u00fchlstrainerin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dc3a5d4 e-flex e-con-boxed e-con e-child\" data-id=\"4dc3a5d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65a6cf5e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"65a6cf5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22e06d9e e-flex e-con-boxed e-con e-child\" data-id=\"22e06d9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72a3a274 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"72a3a274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/in\/ronald-hochstenbach\/\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\"LinkedIn Ronald\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ff24dd2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1ff24dd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/triptherapie.nl\/de\/reservierungen\/ronalds-agenda\/\" target=\"_blank\" aria-label=\"Verf\u00fcgbarkeit Ronald\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60ef8f5a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"60ef8f5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/trip-forum.nl\/recensies-ronald\/\" target=\"_blank\" aria-label=\"Rezensionen Ronald\" rel=\"noopener\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-thumbs-up\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M466.27 286.69C475.04 271.84 480 256 480 236.85c0-44.015-37.218-85.58-85.82-85.58H357.7c4.92-12.81 8.85-28.13 8.85-46.54C366.55 31.936 328.86 0 271.28 0c-61.607 0-58.093 94.933-71.76 108.6-22.747 22.747-49.615 66.447-68.76 83.4H32c-17.673 0-32 14.327-32 32v240c0 17.673 14.327 32 32 32h64c14.893 0 27.408-10.174 30.978-23.95 44.509 1.001 75.06 39.94 177.802 39.94 7.22 0 15.22.01 22.22.01 77.117 0 111.986-39.423 112.94-95.33 13.319-18.425 20.299-43.122 17.34-66.99 9.854-18.452 13.664-40.343 8.99-62.99zm-61.75 53.83c12.56 21.13 1.26 49.41-13.94 57.57 7.7 48.78-17.608 65.9-53.12 65.9h-37.82c-71.639 0-118.029-37.82-171.64-37.82V240h10.92c28.36 0 67.98-70.89 94.54-97.46 28.36-28.36 18.91-75.63 37.82-94.54 47.27 0 47.27 32.98 47.27 56.73 0 39.17-28.36 56.72-28.36 94.54h103.99c21.11 0 37.73 18.91 37.82 37.82.09 18.9-12.82 37.81-22.27 37.81 13.489 14.555 16.371 45.236-5.21 65.62zM88 432c0 13.255-10.745 24-24 24s-24-10.745-24-24 10.745-24 24-24 24 10.745 24 24z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f24ec53 e-flex e-con-boxed e-con e-child\" data-id=\"2f24ec53\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3566a7f9 elementor-widget elementor-widget-image\" data-id=\"3566a7f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/triptherapie.nl\/de\/personal\/janneke\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/05\/d1a043c9-c476-42e9-b5fe-694ffa0ded2f-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-46420\" alt=\"Janneke van de Geijn, vertraulicher Berater und Lifestyle-Coach bei Triptherapie\" srcset=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/05\/d1a043c9-c476-42e9-b5fe-694ffa0ded2f-150x150.png 150w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/05\/d1a043c9-c476-42e9-b5fe-694ffa0ded2f-300x300.png 300w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/05\/d1a043c9-c476-42e9-b5fe-694ffa0ded2f-1024x1024.png 1024w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/05\/d1a043c9-c476-42e9-b5fe-694ffa0ded2f-768x768.png 768w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/05\/d1a043c9-c476-42e9-b5fe-694ffa0ded2f-12x12.png 12w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/05\/d1a043c9-c476-42e9-b5fe-694ffa0ded2f.png 1200w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-603119c5 e-flex e-con-boxed e-con e-child\" data-id=\"603119c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d48cd64 elementor-widget elementor-widget-heading\" data-id=\"5d48cd64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"janneke-van-de-geijn\"><a href=\"https:\/\/triptherapie.nl\/de\/personal\/janneke\/\">Janneke van de Geijn<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b2a243 elementor-widget elementor-widget-heading\" data-id=\"1b2a243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Vertraulicher Berater &amp; Psychedelischer F\u00fchrer<\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e847dfa e-flex e-con-boxed e-con e-child\" data-id=\"1e847dfa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15a69273 elementor-widget elementor-widget-heading\" data-id=\"15a69273\" data-element_type=\"widget\" data-e-type=\"widget\" aria-label=\"Sprachtherapeut\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> \ud83c\uddf3\ud83c\uddf1 \ud83c\uddec\ud83c\udde7 <\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffa7194 e-con-full e-flex e-con e-child\" data-id=\"ffa7194\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab8b382 elementor-invisible elementor-widget elementor-widget-global elementor-global-46899 elementor-widget-counter\" data-id=\"ab8b382\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" aria-live=\"polite\" aria-label=\"Anzahl der gef\u00fchrten psychedelischen Sitzungen\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Sitzungen<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1250\" data-to-value=\"334\" data-from-value=\"326\">326<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a67aad4 elementor-widget elementor-widget-text-editor\" data-id=\"1a67aad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Janneke studiert Angewandte Psychologie, ist Lifestyle-Coach, nimmt Erstkontakte mit Klienten auf, entwickelt individuelle Lebenspl\u00e4ne und erledigt administrative Aufgaben. Sie bietet au\u00dferdem vertrauliche Beratung an. Dar\u00fcber hinaus leitet sie in begrenztem Umfang Sitzungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61942469 e-flex e-con-boxed e-con e-child\" data-id=\"61942469\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75e9d488 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"75e9d488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e029c28 e-flex e-con-boxed e-con e-child\" data-id=\"3e029c28\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-304dbe4e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"304dbe4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/in\/janneke-van-de-geijn-7414b426\/\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\"LinkedIn Janneke\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-246cc822 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"246cc822\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/triptherapie.nl\/de\/reservierungen\/agenda-janneke\/\" target=\"_blank\" aria-label=\"Verf\u00fcgbarkeit Janneke\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e530bc1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7e530bc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/trip-forum.nl\/review-janneke\/\" target=\"_blank\" aria-label=\"Rezensionen Janneke\" rel=\"noopener\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-thumbs-up\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M466.27 286.69C475.04 271.84 480 256 480 236.85c0-44.015-37.218-85.58-85.82-85.58H357.7c4.92-12.81 8.85-28.13 8.85-46.54C366.55 31.936 328.86 0 271.28 0c-61.607 0-58.093 94.933-71.76 108.6-22.747 22.747-49.615 66.447-68.76 83.4H32c-17.673 0-32 14.327-32 32v240c0 17.673 14.327 32 32 32h64c14.893 0 27.408-10.174 30.978-23.95 44.509 1.001 75.06 39.94 177.802 39.94 7.22 0 15.22.01 22.22.01 77.117 0 111.986-39.423 112.94-95.33 13.319-18.425 20.299-43.122 17.34-66.99 9.854-18.452 13.664-40.343 8.99-62.99zm-61.75 53.83c12.56 21.13 1.26 49.41-13.94 57.57 7.7 48.78-17.608 65.9-53.12 65.9h-37.82c-71.639 0-118.029-37.82-171.64-37.82V240h10.92c28.36 0 67.98-70.89 94.54-97.46 28.36-28.36 18.91-75.63 37.82-94.54 47.27 0 47.27 32.98 47.27 56.73 0 39.17-28.36 56.72-28.36 94.54h103.99c21.11 0 37.73 18.91 37.82 37.82.09 18.9-12.82 37.81-22.27 37.81 13.489 14.555 16.371 45.236-5.21 65.62zM88 432c0 13.255-10.745 24-24 24s-24-10.745-24-24 10.745-24 24-24 24 10.745 24 24z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e840754 e-flex e-con-boxed e-con e-child\" data-id=\"4e840754\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7077ec02 elementor-widget elementor-widget-image\" data-id=\"7077ec02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/triptherapie.nl\/de\/personal\/reineke\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Reineke-Brandt-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-56122\" alt=\"Reineke Brandt\" srcset=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Reineke-Brandt-150x150.png 150w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Reineke-Brandt-300x300.png 300w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Reineke-Brandt-12x12.png 12w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Reineke-Brandt.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a4b2e16 e-flex e-con-boxed e-con e-child\" data-id=\"6a4b2e16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b838e8b elementor-widget elementor-widget-heading\" data-id=\"b838e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"reineke-brandt\"><a href=\"https:\/\/triptherapie.nl\/de\/personal\/reineke\/\">Reineke Brandt<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c3dc40 elementor-widget elementor-widget-heading\" data-id=\"6c3dc40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Psychologe<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a16cfdc elementor-widget elementor-widget-heading\" data-id=\"a16cfdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/vindeenpsycholoog.nip.nl\/?zoeken=1&#038;sort=&#038;naam=&#038;nip=17907&#038;registratie=&#038;deskundigheid=&#038;plaats=&#038;afstand=5#:~:text=Brandt17907\" target=\"_blank\" rel=\"nofollow noopener\">NIP-Nummer: 17907<\/a><\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25d4c308 e-flex e-con-boxed e-con e-child\" data-id=\"25d4c308\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e242743 elementor-widget elementor-widget-heading\" data-id=\"1e242743\" data-element_type=\"widget\" data-e-type=\"widget\" aria-label=\"Sprachtherapeut\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> \ud83c\uddf3\ud83c\uddf1 \ud83c\uddec\ud83c\udde7 \ud83c\udde9\ud83c\uddea<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a208d8 e-con-full e-flex e-con e-child\" data-id=\"5a208d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a7ad82 elementor-invisible elementor-widget elementor-widget-global elementor-global-47562 elementor-widget-counter\" data-id=\"3a7ad82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" aria-live=\"polite\" aria-label=\"Anzahl der gef\u00fchrten psychedelischen Sitzungen\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Sitzungen<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"500\" data-to-value=\"195\" data-from-value=\"186\">186<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65e824e1 elementor-widget elementor-widget-text-editor\" data-id=\"65e824e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Als Psychologin kombiniert Reineke konventionelle und alternative Behandlungsmethoden. Sie nutzt verschiedene Techniken wie Gespr\u00e4chstherapie, Yoga, Atem\u00fcbungen und EMDR in Verbindung mit den therapeutischen Wirkungen von Psychedelika.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5bcb5dd4 e-flex e-con-boxed e-con e-child\" data-id=\"5bcb5dd4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5dd3fa63 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5dd3fa63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57090951 e-flex e-con-boxed e-con e-child\" data-id=\"57090951\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77206382 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"77206382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/in\/reineke-brandt-05180317\/\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\"LinkedIn Reineke\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51f845fe elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"51f845fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/triptherapie.nl\/de\/reservierungen\/reinekes-agenda\/#beschikbaarheid-van-reineke\" target=\"_blank\" aria-label=\"Verf\u00fcgbarkeit Reineke\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21c8a494 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"21c8a494\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/trip-forum.nl\/ervaringen-truffel-reineke\/\" target=\"_blank\" aria-label=\"Rezensionen Reineke\" rel=\"noopener\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-thumbs-up\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M466.27 286.69C475.04 271.84 480 256 480 236.85c0-44.015-37.218-85.58-85.82-85.58H357.7c4.92-12.81 8.85-28.13 8.85-46.54C366.55 31.936 328.86 0 271.28 0c-61.607 0-58.093 94.933-71.76 108.6-22.747 22.747-49.615 66.447-68.76 83.4H32c-17.673 0-32 14.327-32 32v240c0 17.673 14.327 32 32 32h64c14.893 0 27.408-10.174 30.978-23.95 44.509 1.001 75.06 39.94 177.802 39.94 7.22 0 15.22.01 22.22.01 77.117 0 111.986-39.423 112.94-95.33 13.319-18.425 20.299-43.122 17.34-66.99 9.854-18.452 13.664-40.343 8.99-62.99zm-61.75 53.83c12.56 21.13 1.26 49.41-13.94 57.57 7.7 48.78-17.608 65.9-53.12 65.9h-37.82c-71.639 0-118.029-37.82-171.64-37.82V240h10.92c28.36 0 67.98-70.89 94.54-97.46 28.36-28.36 18.91-75.63 37.82-94.54 47.27 0 47.27 32.98 47.27 56.73 0 39.17-28.36 56.72-28.36 94.54h103.99c21.11 0 37.73 18.91 37.82 37.82.09 18.9-12.82 37.81-22.27 37.81 13.489 14.555 16.371 45.236-5.21 65.62zM88 432c0 13.255-10.745 24-24 24s-24-10.745-24-24 10.745-24 24-24 24 10.745 24 24z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78189121 e-flex e-con-boxed e-con e-child\" data-id=\"78189121\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3326bd38 elementor-widget elementor-widget-image\" data-id=\"3326bd38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/triptherapie.nl\/de\/personal\/sascha\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Sascha-de-Waal-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-56124\" alt=\"Portrait Sascha de Waal\" srcset=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Sascha-de-Waal-150x150.png 150w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Sascha-de-Waal-300x300.png 300w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Sascha-de-Waal-12x12.png 12w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Sascha-de-Waal.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17c4695d e-flex e-con-boxed e-con e-child\" data-id=\"17c4695d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32db7b38 elementor-widget elementor-widget-heading\" data-id=\"32db7b38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"sascha-de-waal\"><a href=\"https:\/\/triptherapie.nl\/de\/personal\/sascha\/\">Sascha de Waal<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4707ca78 elementor-widget elementor-widget-heading\" data-id=\"4707ca78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Psychologe<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1c82bc elementor-widget elementor-widget-heading\" data-id=\"d1c82bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/vindeenpsycholoog.nip.nl\/?zoeken=1&#038;sort=lastname&#038;naam=&#038;nip=247448&#038;registratie=&#038;deskundigheid=&#038;plaats=&#038;afstand=5#:~:text=S%2EN%2E%20De%20Waal%20MA%2C%20MSc%2C%20BA247448\" target=\"_blank\" rel=\"nofollow noopener\">NIP-Nummer: 247448<\/a><\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdca199 e-flex e-con-boxed e-con e-child\" data-id=\"cdca199\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d08b1ad elementor-widget elementor-widget-heading\" data-id=\"d08b1ad\" data-element_type=\"widget\" data-e-type=\"widget\" aria-label=\"Sprachtherapeut\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> \ud83c\uddf3\ud83c\uddf1 \ud83c\uddec\ud83c\udde7 <\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4aa1bb e-con-full e-flex e-con e-child\" data-id=\"a4aa1bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad114b elementor-invisible elementor-widget elementor-widget-global elementor-global-46911 elementor-widget-counter\" data-id=\"5ad114b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" aria-live=\"polite\" aria-label=\"Anzahl der gef\u00fchrten psychedelischen Sitzungen\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Sitzungen<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"750\" data-to-value=\"172\" data-from-value=\"169\">169<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64e57a7c elementor-widget elementor-widget-text-editor\" data-id=\"64e57a7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Sascha verf\u00fcgt dank ihres Psychologiestudiums, ihres Masterabschlusses in Klinischer Psychologie und ihrer Berufserfahrung als Psychologin in der Suchtbehandlung, der (spezialisierten) psychiatrischen Versorgung und der Rehabilitation \u00fcber eine solide Grundlage als psychedelische Therapeutin. Sie hat au\u00dferdem Zusatzausbildungen in kognitiver Verhaltenstherapie und EMDR absolviert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f1d8a7d e-flex e-con-boxed e-con e-child\" data-id=\"3f1d8a7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19f5a8b7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"19f5a8b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c789d90 e-flex e-con-boxed e-con e-child\" data-id=\"4c789d90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21ba4a2e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"21ba4a2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/in\/sascha-de-waal-69398927\/\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\"LinkedIn Sascha\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdee007 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cdee007\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/triptherapie.nl\/de\/reservierungen\/verfugbarkeit-sascha\/\" target=\"_blank\" aria-label=\"Verf\u00fcgbarkeit Sascha\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6711ea56 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6711ea56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/trip-forum.nl\/recensies-sascha\/\" target=\"_blank\" aria-label=\"Rezensionen Sascha\" rel=\"noopener\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-thumbs-up\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M466.27 286.69C475.04 271.84 480 256 480 236.85c0-44.015-37.218-85.58-85.82-85.58H357.7c4.92-12.81 8.85-28.13 8.85-46.54C366.55 31.936 328.86 0 271.28 0c-61.607 0-58.093 94.933-71.76 108.6-22.747 22.747-49.615 66.447-68.76 83.4H32c-17.673 0-32 14.327-32 32v240c0 17.673 14.327 32 32 32h64c14.893 0 27.408-10.174 30.978-23.95 44.509 1.001 75.06 39.94 177.802 39.94 7.22 0 15.22.01 22.22.01 77.117 0 111.986-39.423 112.94-95.33 13.319-18.425 20.299-43.122 17.34-66.99 9.854-18.452 13.664-40.343 8.99-62.99zm-61.75 53.83c12.56 21.13 1.26 49.41-13.94 57.57 7.7 48.78-17.608 65.9-53.12 65.9h-37.82c-71.639 0-118.029-37.82-171.64-37.82V240h10.92c28.36 0 67.98-70.89 94.54-97.46 28.36-28.36 18.91-75.63 37.82-94.54 47.27 0 47.27 32.98 47.27 56.73 0 39.17-28.36 56.72-28.36 94.54h103.99c21.11 0 37.73 18.91 37.82 37.82.09 18.9-12.82 37.81-22.27 37.81 13.489 14.555 16.371 45.236-5.21 65.62zM88 432c0 13.255-10.745 24-24 24s-24-10.745-24-24 10.745-24 24-24 24 10.745 24 24z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-693d25a0 e-flex e-con-boxed e-con e-child\" data-id=\"693d25a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73b65a8 elementor-widget elementor-widget-image\" data-id=\"73b65a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/triptherapie.nl\/de\/personal\/gijs\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Gijs-Tecklenburg-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-56125\" alt=\"\" srcset=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Gijs-Tecklenburg-150x150.png 150w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Gijs-Tecklenburg-300x300.png 300w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Gijs-Tecklenburg-12x12.png 12w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Gijs-Tecklenburg.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6bca41ed e-flex e-con-boxed e-con e-child\" data-id=\"6bca41ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f201138 elementor-widget elementor-widget-heading\" data-id=\"3f201138\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"gijs-tecklenburg\"><a href=\"https:\/\/triptherapie.nl\/de\/personal\/gijs\/\">Gijs Tecklenburg<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c044999 elementor-widget elementor-widget-heading\" data-id=\"5c044999\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">SPV-er<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6dd116 elementor-widget elementor-widget-heading\" data-id=\"f6dd116\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.vektis.nl\/agb-register\/zorgverlener-90036329\" target=\"_blank\" rel=\"nofollow noopener\">VMBN-Registrierung mit AGB-Code: 90036329<\/a><\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d580493 e-flex e-con-boxed e-con e-child\" data-id=\"6d580493\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-424da49c elementor-widget elementor-widget-heading\" data-id=\"424da49c\" data-element_type=\"widget\" data-e-type=\"widget\" aria-label=\"Sprachtherapeut\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> \ud83c\uddf3\ud83c\uddf1 \ud83c\uddec\ud83c\udde7 \ud83c\udde9\ud83c\uddea<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2ea631 e-con-full e-flex e-con e-child\" data-id=\"f2ea631\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce7e09 elementor-invisible elementor-widget elementor-widget-global elementor-global-46905 elementor-widget-counter\" data-id=\"3ce7e09\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" aria-live=\"polite\" aria-label=\"Anzahl der gef\u00fchrten psychedelischen Sitzungen\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Sitzungen<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"250\" data-to-value=\"93\" data-from-value=\"91\" data-delimiter=\",\">91<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bc05e27 elementor-widget elementor-widget-text-editor\" data-id=\"3bc05e27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Gijs verf\u00fcgt \u00fcber 20 Jahre Erfahrung in der ambulanten psychiatrischen Versorgung. Er lehrte und betreute den Studiengang \u201ePsychische Gesundheit und Suchtbehandlung\u201c an der HAN University of Applied Sciences Arnhem Nijmegen. Dar\u00fcber hinaus besitzt er umfassende Erfahrung in Achtsamkeit, Gespr\u00e4chstherapie, Neurofeedback, Meditation, Mitgef\u00fchlstraining und Akzeptanz- und Commitmenttherapie (ACT).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4994628c e-flex e-con-boxed e-con e-child\" data-id=\"4994628c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37d667dd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"37d667dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66eddd1c e-flex e-con-boxed e-con e-child\" data-id=\"66eddd1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e57792b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5e57792b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/in\/gijs-tecklenburg-21526520\/\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\"LinkedIn Gijs\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46739d56 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"46739d56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/triptherapie.nl\/de\/reservierungen\/verfugbarkeit-gijs\/\" target=\"_blank\" aria-label=\"Verf\u00fcgbarkeit Gijs\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-284bf1ca elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"284bf1ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/trip-forum.nl\/recensies-gijs\/\" target=\"_blank\" aria-label=\"Rezensionen Gijs\" rel=\"noopener\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-thumbs-up\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M466.27 286.69C475.04 271.84 480 256 480 236.85c0-44.015-37.218-85.58-85.82-85.58H357.7c4.92-12.81 8.85-28.13 8.85-46.54C366.55 31.936 328.86 0 271.28 0c-61.607 0-58.093 94.933-71.76 108.6-22.747 22.747-49.615 66.447-68.76 83.4H32c-17.673 0-32 14.327-32 32v240c0 17.673 14.327 32 32 32h64c14.893 0 27.408-10.174 30.978-23.95 44.509 1.001 75.06 39.94 177.802 39.94 7.22 0 15.22.01 22.22.01 77.117 0 111.986-39.423 112.94-95.33 13.319-18.425 20.299-43.122 17.34-66.99 9.854-18.452 13.664-40.343 8.99-62.99zm-61.75 53.83c12.56 21.13 1.26 49.41-13.94 57.57 7.7 48.78-17.608 65.9-53.12 65.9h-37.82c-71.639 0-118.029-37.82-171.64-37.82V240h10.92c28.36 0 67.98-70.89 94.54-97.46 28.36-28.36 18.91-75.63 37.82-94.54 47.27 0 47.27 32.98 47.27 56.73 0 39.17-28.36 56.72-28.36 94.54h103.99c21.11 0 37.73 18.91 37.82 37.82.09 18.9-12.82 37.81-22.27 37.81 13.489 14.555 16.371 45.236-5.21 65.62zM88 432c0 13.255-10.745 24-24 24s-24-10.745-24-24 10.745-24 24-24 24 10.745 24 24z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25ed1a7 e-flex e-con-boxed e-con e-child\" data-id=\"25ed1a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-982944f elementor-widget elementor-widget-image\" data-id=\"982944f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Ylva-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-54561\" alt=\"Ylva Doorewaard Boekhout, klinische Psychologin und Triptherapie-Beraterin\" srcset=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Ylva-150x150.png 150w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Ylva-300x300.png 300w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Ylva-12x12.png 12w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2024\/06\/Ylva.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-360cb9a e-flex e-con-boxed e-con e-child\" data-id=\"360cb9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16163bd elementor-widget elementor-widget-heading\" data-id=\"16163bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"ylva-doorewaard-boekhout\">Ylva Doorewaard Boekhout<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb1f1b2 elementor-widget elementor-widget-heading\" data-id=\"cb1f1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Klinischer Psychologe<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cec2b0 elementor-widget elementor-widget-heading\" data-id=\"4cec2b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/zoeken.bigregister.nl\/zorgverlener\/7db99b46-675d-4ed8-bfee-b5724e5f0b0f\" target=\"_blank\" rel=\"nofollow noopener\">GROSSE Zahl: 19930515225<\/a><\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d15383 e-con-full e-flex e-con e-child\" data-id=\"8d15383\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67df4d9 elementor-widget elementor-widget-heading\" data-id=\"67df4d9\" data-element_type=\"widget\" data-e-type=\"widget\" aria-label=\"Sprachtherapeut\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"> \ud83c\uddf3\ud83c\uddf1 \ud83c\uddec\ud83c\udde7 <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b5766b e-con-full e-flex e-con e-child\" data-id=\"8b5766b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e855b8 elementor-widget elementor-widget-heading\" data-id=\"7e855b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"ondersteunend-therapeut\">Unterst\u00fctzender Therapeut<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e474022 elementor-widget elementor-widget-text-editor\" data-id=\"e474022\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ylva ist eine bei BIG registrierte Psychologin aus Genf und unterst\u00fctzt Triptherapie als Beraterin in den Bereichen psychologische Betreuung, Konzepte der psychischen Gesundheit, Sicherheit und Integration. Ylva bietet keine psychedelischen Sitzungen an, steht aber f\u00fcr zus\u00e4tzliche Unterst\u00fctzung zur Verf\u00fcgung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b99086 e-flex e-con-boxed e-con e-child\" data-id=\"9b99086\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb55741 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"eb55741\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-085c871 e-flex e-con-boxed e-con e-child\" data-id=\"085c871\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa8650 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2fa8650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/in\/ylva-doorewaard-boekhout-603a1832\/\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\"LinkedIn Gijs\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Legale LSD sessie in Nederland In Nederland is LSD illegaal omdat het op de Opiumlijst staat als een harddrug met een hoge mate van gevaar en verslavende eigenschappen. LSD is geclassificeerd als een Schedule 1 drug, wat betekent dat het wordt beschouwd als een substantie zonder medische waarde en met een hoog risico op misbruik [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2383,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-42705","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/pages\/42705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/comments?post=42705"}],"version-history":[{"count":0,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/pages\/42705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/media\/2383"}],"wp:attachment":[{"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/media?parent=42705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}