{"id":2020,"date":"2019-05-21T10:52:10","date_gmt":"2019-05-21T09:52:10","guid":{"rendered":"https:\/\/triptherapie.nl\/?p=2020"},"modified":"2026-02-12T08:36:55","modified_gmt":"2026-02-12T07:36:55","slug":"psychedelische-therapie-bei-todesangst","status":"publish","type":"post","link":"https:\/\/triptherapie.nl\/de\/psychedelische-therapie-tegen-doodsangst\/","title":{"rendered":"Psychedelische Therapie bei Todesangst"},"content":{"rendered":"<h2 class=\"wp-block-heading has-text-align-center\" id=\"psychedelische-therapie\">Psychedelische Therapie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die psychedelische Therapie bei Angstzust\u00e4nden gilt als eine der wirksamsten bekannten Therapieformen. Sie kann zur Behandlung von Depressionen, Angstzust\u00e4nden, Stress, Burnout und anderen psychischen St\u00f6rungen und\/oder Beschwerden eingesetzt werden. Im Folgenden wird die Psilocybin-Therapie f\u00fcr unheilbar an Krebs erkrankte Patienten beschrieben.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-purple-background-color has-background has-small-font-size has-custom-font-size wp-element-button\" href=\"https:\/\/triptherapie.nl\/de\/psychedelische-therapie\/\" style=\"border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-left-radius:5px;border-bottom-right-radius:5px\">Psychedelische Therapie<\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"terminale-kanker-en-psilocybine\">Krebs im Endstadium und Psilocybin<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Als Pam Sakuda von ihren \u00c4rzten erfuhr, dass sich ihr Krebs ausgebreitet hatte und nichts mehr getan werden konnte, \u00fcberw\u00e4ltigte sie die Angst vor dem Tod.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMan kann nicht mehr alle Pl\u00e4ne umsetzen, die man hatte\u201d, sagte sie in einem Videointerview vor ihrem Tod im Jahr 2006. \u201cMan lebt im Grunde in Angst. \u2026 Es l\u00e4hmt das gute Leben, das man im Moment f\u00fchrt.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deshalb griff Sakuda zu Halluzinogenen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Hoffnung, \u2018einen Weg zum inneren Frieden zu finden\u2019, nahm sie 2004 an einer Pilotstudie unter der Leitung des Psychiaters Charles Grob am Harbor-UCLA Medical Center in Los Angeles teil. Grob kombinierte Sakudas regul\u00e4re Gespr\u00e4chstherapie mit einer Einzeldosis Psilocybin, dem Wirkstoff in halluzinogenen Pilzen und Zaubertr\u00fcffeln. Die US-amerikanische Arzneimittelbeh\u00f6rde FDA hat Psilocybin \u00fcbrigens k\u00fcrzlich f\u00fcr klinische Studien zur Behandlung von Angstzust\u00e4nden am Lebensende (Todesangst) zugelassen.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" width=\"590\" height=\"350\" src=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2019\/05\/doodsangst.jpg\" alt=\"\" class=\"wp-image-2021\" title=\"\" srcset=\"https:\/\/triptherapie.nl\/wp-content\/uploads\/2019\/05\/doodsangst.jpg 590w, https:\/\/triptherapie.nl\/wp-content\/uploads\/2019\/05\/doodsangst-300x178.jpg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/><figcaption class=\"wp-element-caption\">Ein Psilocybin-Trip kann bei hohen Dosen einem Nahtoderlebnis \u00e4hneln.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sakuda glaubte, dass Psilocybin ihr geholfen habe, das Leben wertzusch\u00e4tzen. \u201cEs erm\u00f6glicht einem, andere Gef\u00fchle loszulassen und andere Empfindungen zu entdecken\u201d, sagte sie. \u201cMir wurde klar, dass all diese negative Angst ein Hindernis daf\u00fcr war, die mir verbleibende gesunde Zeit \u2013 wie lang sie auch sein mag \u2013 voll auszukosten und zu genie\u00dfen.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie war nicht allein. Bei den 12 Patienten, die er mit Psilocybin behandelte, fand Grob erste Hinweise auf eine Verringerung der Angstzust\u00e4nde sowie eine Verbesserung der Stimmung und Lebensqualit\u00e4t. Zudem gab es Anzeichen daf\u00fcr, dass diese positiven Effekte mehrere Monate anhielten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um Grobs Arbeit fortzuf\u00fchren, rekrutieren Psychiater der Johns Hopkins University und der New York University derzeit Patienten f\u00fcr \u00e4hnliche Studien. Solche Studien haben eine Forschungswelle ausgel\u00f6st, die neue Behandlungsmethoden f\u00fcr psychische Erkrankungen und ein neues Verst\u00e4ndnis unseres Gehirns verspricht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs scheint, dass diese sehr, sehr intensive Erfahrung den Einzelnen zu mehr innerem Frieden verhilft\u201d, sagte Grob, der plant, seine Ergebnisse noch in diesem Jahr zu ver\u00f6ffentlichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut Stephen Ross, der die Studie der New York University leitete, gibt es f\u00fcr \u00c4rzte keine Standardverfahren im Umgang mit den Bed\u00fcrfnissen eines Patienten am Lebensende, und diese Angst wird oft ignoriert.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAls \u00c4rzte sind wir gut darin, Leben zu retten\u201d, sagte Ross. \u201cAber wir haben die Kunst noch nicht gelernt, Patienten ein w\u00fcrdevolles Sterben zu erm\u00f6glichen.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine 2007 von der American Cancer Society ver\u00f6ffentlichte Studie ergab, dass bei bis zu 50 Prozent der Patienten mit fortgeschrittenem oder unheilbarem Krebs eine schwere psychiatrische St\u00f6rung diagnostiziert wird und dass weniger als die H\u00e4lfte der Patienten mit depressiven Symptomen psychiatrische Medikamente erhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut den Forschern kann Psilocybin in einer einzigen Sitzung das erreichen, wof\u00fcr man sonst Monate oder Jahre br\u00e4uchte \u2013 Zeit, die manche dieser Patienten m\u00f6glicherweise nicht haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Psilocybin bindet an zwei Arten von Serotoninrezeptoren im Gehirn, die eng mit Stimmung und Angstzust\u00e4nden verkn\u00fcpft sind. Noch interessanter f\u00fcr Psychiater: Bildgebende Verfahren des Heffter Forschungszentrums in der Schweiz zeigen, dass die Substanz offenbar auch Hirnareale beeinflusst, die vermutlich Bewusstsein und spirituelle Gef\u00fchle vermitteln.<\/p>\n\n\n\n<p class=\"has-link-color wp-elements-1 wp-block-paragraph\">Der <a href=\"https:\/\/triptherapie.nl\/de\/psychedelika\/psilocybin\/#de-subjectieve-beleving\">Wirkungen von Psilocybin<\/a> Die Wirkung h\u00e4lt etwa vier bis sechs Stunden an. In dieser Zeit \u00e4hnelt die Gehirnaktivit\u00e4t der Teilnehmer derjenigen von Menschen in spirituellen Zust\u00e4nden, wie beispielsweise meditierenden M\u00f6nchen. \u00c4hnlich wie Menschen, die Meditation praktizieren, berichteten die Patienten in den Psilocybin-Studien von Gef\u00fchlen wie einer st\u00e4rkeren Verbundenheit mit anderen, Linderung von Angstzust\u00e4nden und der F\u00e4higkeit, ihre begrenzte Zeit als Chance f\u00fcr pers\u00f6nliches Wachstum zu begreifen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPatienten, die Psilocybin einnehmen, kn\u00fcpfen Verbindungen zu tieferen Schichten ihrer Psyche, die ihnen normalerweise verschlossen bleiben\u201d, sagte Ross. \u201cSie k\u00f6nnen bestimmte Zusammenh\u00e4nge herstellen, die sie sonst nicht herstellen w\u00fcrden.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Wirkmechanismus des Medikaments ist jedoch noch nicht vollst\u00e4ndig erforscht, weshalb die Langzeitrisiken unklar sind. Laut David Shurtleff, Leiter der Abteilung f\u00fcr Grundlagenforschung in der Neurowissenschaft am National Institute of Drug Abuse in Bethesda, Maryland, sind die Wirkungen des Medikaments sehr variabel und es sollte nur unter kontrollierten Bedingungen eingenommen werden. Im Gegensatz zu anderen Drogen deuten die Erkenntnisse jedoch auf ein geringes Missbrauchspotenzial hin. Psilocybin scheint nicht k\u00f6rperlich abh\u00e4ngig zu machen, unter anderem weil Ratten es nicht wie Nikotin, Alkohol und Kokain selbst verabreichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund erster positiver Ergebnisse aus Studien zur Behandlung von Sterbebegleitung wollen Ross und andere Forscher Psilocybin zur Behandlung von Tabak-, Alkohol- und Drogenabh\u00e4ngigkeit testen. \u201cS\u00fcchtige haben eine zwanghafte, zerr\u00fcttete Beziehung, die sich ausschlie\u00dflich auf die Droge und nichts anderes beschr\u00e4nkt\u201d, sagte Ross. \u201cPsilocybin kann ihrem Leben helfen, Sinn, Richtung, Ziel und Verbundenheit zur\u00fcckzugewinnen.\u201d <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Letztendlich hoffen die Wissenschaftler, dass diese Studien dazu beitragen werden, die Neurobiologie der Spiritualit\u00e4t zu kl\u00e4ren. \u201cDie Tatsache, dass wir \u00fcber Nervengewebe verf\u00fcgen, das diese Erfahrungen erm\u00f6glicht, zeigt, dass sich das Gehirn so entwickelt hat, dass es spirituelle Erfahrungen erm\u00f6glicht\u201d, sagte Ross.<\/p>","protected":false},"excerpt":{"rendered":"<p>Psychedelische therapie Psychedelische therapie tegen angst is de sterkste vorm van therapie die we kennen. Het kan worden ingezet tegen depressie, angsten, stress, burn-out en andere psychische stoornissen en\/of klachten. Het onderstaande stuk gaat over psilocybine therapie bij terminale kanker pati\u00ebnten. Terminale kanker en psilocybine Toen haar artsen Pam Sakuda vertelden dat haar kanker uitgezaaid [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-2020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nieuws"],"_links":{"self":[{"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/posts\/2020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/comments?post=2020"}],"version-history":[{"count":0,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/posts\/2020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/media\/2021"}],"wp:attachment":[{"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/media?parent=2020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/categories?post=2020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triptherapie.nl\/de\/wp-json\/wp\/v2\/tags?post=2020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}